{"id":2514,"date":"2021-09-16T12:43:36","date_gmt":"2021-09-16T11:43:36","guid":{"rendered":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/?p=2514"},"modified":"2021-09-16T12:43:37","modified_gmt":"2021-09-16T11:43:37","slug":"vale-da-ribeira-de-cortico-2021-03-26-2514","status":"publish","type":"post","link":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/","title":{"rendered":"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2514","post","type-post","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514 - Birdwatching<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514 - Birdwatching\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/\" \/>\n<meta property=\"og:site_name\" content=\"Birdwatching\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T11:43:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-16T11:43:37+00:00\" \/>\n<meta name=\"author\" content=\"Luis Novo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Novo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/vale-da-ribeira-de-cortico-2021-03-26-2514\\\/\",\"url\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/vale-da-ribeira-de-cortico-2021-03-26-2514\\\/\",\"name\":\"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\\\/03\\\/26 - 2514 - Birdwatching\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/#website\"},\"datePublished\":\"2021-09-16T11:43:36+00:00\",\"dateModified\":\"2021-09-16T11:43:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/#\\\/schema\\\/person\\\/9a2d0e9b73f955fe53c2fcbbb4a17725\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/vale-da-ribeira-de-cortico-2021-03-26-2514\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/vale-da-ribeira-de-cortico-2021-03-26-2514\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/vale-da-ribeira-de-cortico-2021-03-26-2514\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vale da Ribeira de Corti\u00e7\u00f4 &#8211; 2021\\\/03\\\/26 &#8211; 2514\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/#website\",\"url\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/\",\"name\":\"Birdwatching\",\"description\":\"Mais um site Sites de Munic\u00edpio de Fornos de Algodres\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cm-fornosdealgodres.pt\\\/birdwatching\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514 - Birdwatching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/","og_locale":"pt_PT","og_type":"article","og_title":"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514 - Birdwatching","og_url":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/","og_site_name":"Birdwatching","article_published_time":"2021-09-16T11:43:36+00:00","article_modified_time":"2021-09-16T11:43:37+00:00","author":"Luis Novo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Novo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/","url":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/","name":"Vale da Ribeira de Corti\u00e7\u00f4 - 2021\/03\/26 - 2514 - Birdwatching","isPartOf":{"@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/#website"},"datePublished":"2021-09-16T11:43:36+00:00","dateModified":"2021-09-16T11:43:37+00:00","author":{"@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/#\/schema\/person\/9a2d0e9b73f955fe53c2fcbbb4a17725"},"breadcrumb":{"@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/vale-da-ribeira-de-cortico-2021-03-26-2514\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/"},{"@type":"ListItem","position":2,"name":"Vale da Ribeira de Corti\u00e7\u00f4 &#8211; 2021\/03\/26 &#8211; 2514"}]},{"@type":"WebSite","@id":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/#website","url":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/","name":"Birdwatching","description":"Mais um site Sites de Munic\u00edpio de Fornos de Algodres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"tag_names":[],"_links":{"self":[{"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/posts\/2514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/comments?post=2514"}],"version-history":[{"count":0,"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/posts\/2514\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cm-fornosdealgodres.pt\/birdwatching\/wp-json\/wp\/v2\/media?parent=2514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}